{"id":26290,"date":"2016-05-21T12:00:19","date_gmt":"2016-05-21T10:00:19","guid":{"rendered":"https:\/\/www.thomann.de\/blog\/?p=26290"},"modified":"2020-05-11T17:55:33","modified_gmt":"2020-05-11T15:55:33","slug":"rig-rundown-interview-mit-blind-guardian","status":"publish","type":"post","link":"https:\/\/www.thomann.de\/blog\/de\/inspire\/rig-rundown-interview-mit-blind-guardian\/","title":{"rendered":"Rig-Rundown &#038; Interview mit Blind Guardian"},"content":{"rendered":"<p>F\u00fcr den \u201e<strong>deutschen Metal<\/strong>\u201d hat der <strong>Ruhrpott<\/strong> eine zentrale Rolle gespielt. Hier bildeten sich in den 1970er und 80er Jahren zahlreiche Bands, die, zun\u00e4chst ihre Helden kopierend, nach und nach eigene Sounds und Stilrichtungen schufen. Kein Wunder also, dass das seit 2003 im Herzen des Reviers ausgetragene <a href=\"https:\/\/www.rockhard.de\/festival\/infos\/news.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Rock Hard Festival<\/strong><\/a> bei seiner bereits 18. Auflage vom 13. bis 15. Mai 2016 in besonderem Ma\u00dfe auf heimische Bands setzt. Neben internationalen Gr\u00f6\u00dfen wie <strong>Cannibal Corpse<\/strong> und <strong>Turbonegro<\/strong> standen so speziell der Freitag (u. a. <strong>Tankard<\/strong>, <strong>Destruction<\/strong> und <strong>Sodom<\/strong>) sowie der Sonntag im Zeichen des \u201eGerman Metal\u201d, und so fand das Festival mit den Fantasy-Metal-Helden von <strong>Blind Guardian<\/strong> einen krachenden Abschluss.<\/p>\n<p>Ein paar Stunden vor dem Gig bekamen wir zudem noch die M\u00f6glichkeit, Blind-Guardian-Gitarrero <strong>Marcus Siepen<\/strong> ausgiebig zu seinem Live-Equipment zu befragen \u2026<\/p>\n<p><strong>Kannst du uns einen \u00dcberblick \u00fcber das Gear der aktuellen Tour geben?<\/strong><\/p>\n<p><a href=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-26301\" src=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-1-300x225.jpg\" alt=\"Marcus mit seiner Les Paul Custom\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-1-300x225.jpg 300w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-1-1024x769.jpg 1024w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-1-768x577.jpg 768w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-1.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u201eGitarrentechnisch bin ich eigentlich komplett mit <a href=\"http:\/\/www.thomann.de\/de\/gibson.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Gibson<\/strong><\/a> unterwegs seit vielen, vielen Jahren. Bin Liebhaber, Sammler, Endorser, &#8230; Haupts\u00e4chlich <a href=\"http:\/\/www.thomann.de\/de\/lp-modelle.html?filter=true&amp;manufacturer%5B0%5D=Gibson&amp;viewMode=block\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Les Pauls<\/strong><\/a>, davon verschiedenste Modelle: <strong>Les Paul Custom<\/strong>, <strong>Standard, Premium<\/strong>, <strong>Plus<\/strong>, <strong>Classic<\/strong>, eine <strong>Siebensaiter<\/strong>, eine <strong>Traditional<\/strong>, alles querbeet. Ich hab jetzt gerade f\u00fcr diesen Run ein bisschen neu best\u00fcckt \u2013 ich hatte letztes Jahr ein paar andere dabei, aber man will ja auch mal wechseln. Unabh\u00e4ngig von den Les Pauls hab ich grade neu eine <a href=\"http:\/\/www.thomann.de\/de\/gibson_sg_light_7.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>siebensaitige SG<\/strong><\/a>, an der ich gro\u00dfen Spa\u00df habe. Die ist gerade neu rausgekommen, limitiert auf 300 St\u00fcck, und ich bin einer der gl\u00fccklichen Besitzer. Eine <strong>Flying V<\/strong>, eine<strong> Explorer<\/strong> \u2013 wie gesagt: alles Gibson. Das meiste davon ist mit <a href=\"http:\/\/www.thomann.de\/de\/search.html?sw=EMG&amp;filter=true&amp;manufacturer%5B%5D=EMG&amp;viewMode=block\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>EMG<\/strong><\/a>s best\u00fcckt, meistens zwei St\u00fcck der <a href=\"http:\/\/www.thomann.de\/de\/emg_81.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>81er<\/strong><\/a>, <a href=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-26302 alignright\" src=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-2-225x300.jpg\" alt=\"Der &quot;Gitarrenparkplatz&quot;\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-2-225x300.jpg 225w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-2-769x1024.jpg 769w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-2-768x1023.jpg 768w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-2.jpg 901w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>alternativ auch <strong><a href=\"http:\/\/www.thomann.de\/de\/emg_66_n_bbc_humbucker_pickup.htm\" target=\"_blank\" rel=\"noopener noreferrer\">57er<\/a><\/strong> oder <a href=\"http:\/\/www.thomann.de\/de\/emg_66_n_bbc_humbucker_pickup.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>66er<\/strong><\/a> am Hals. Zwei sind auch mit <strong><a href=\"http:\/\/www.thomann.de\/de\/seymour_duncan_black_winter_set.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Seymour-Duncan-Pickups<\/a><\/strong> best\u00fcckt: Die Explorer hat das Black-Winter-Set, was ich sehr mag, und die siebensaitige Les Paul hat das <a href=\"http:\/\/www.thomann.de\/de\/seymour_duncan_nazgul_sentient_7_set_bk.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Nazgul-Sentient-Set<\/strong><\/a>. Eine hat auch von <strong>John Suhr<\/strong> die <a href=\"http:\/\/www.thomann.de\/de\/suhr_humbucker_tonabnehmer.html?viewMode=block\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Doug-Aldrich-Pickups<\/strong><\/a>, die Signature-Pickups von ihm, die ich sehr, sehr mag. F\u00fcr akustische Sachen hab ich zwei<a href=\"http:\/\/www.thomann.de\/de\/epiphone.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong> Epiphone<\/strong><\/a>\u00a0<strong>SST<\/strong>\u00a0Studio, das sind im Prinzip Kopien der damaligen <strong>Chet-Atkins-Solidbody-Akustik<\/strong>. Die hat den Vorteil, dass du live egal bei welcher Lautst\u00e4rke keinerlei Feedback-Probleme hast und sie klingt hervorragend. Normalerweise w\u00fcrde ich eine <strong><a href=\"http:\/\/www.thomann.de\/de\/gibson_j45_rosewood_custom_vs.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Gibson J45<\/a><\/strong> spielen, die ich im Studio nutze \u2013 aber auf der B\u00fchne \u2026 Eine <a href=\"http:\/\/www.thomann.de\/de\/gitarren_baesse.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Akustikgitarre<\/strong><\/a> schwingt sich ab einer gewissen Lautst\u00e4rke halt einfach auf und mit den SSTs haben wir \u00fcberhaupt keinen Stress \u2013 es ist egal wie laut es ist, das geht immer.\u201c<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-26290 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-13-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><strong>Und Amps?<\/strong><\/p>\n<p style=\"text-align: left;\">\u201eIn Sachen Amps bin ich komplett mit zwei <strong>Fractal Audio AXE-FX II XL<\/strong> unterwegs, die sind identisch programmiert. Das hei\u00dft einer ist der Main-Amp, einer ist der Backup. Ich benutze sechs verschiedene Presets im Moment mit je f\u00fcnf Scenes. Die <strong>Scenes<\/strong> sind alle gleich <a href=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-26303 size-medium\" src=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-3-300x225.jpg\" alt=\"Marcus' Pedalboard mit Mission-Expression-Pedal\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-3-300x225.jpg 300w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-3-1024x769.jpg 1024w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-3-768x577.jpg 768w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-3.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>aufgesetzt, dar\u00fcber ruf ich halt Rhythmussound, Clean-, Crunch-, Lead- und Solosound ab. Und die eigentlichen <strong>Presets<\/strong> benutze ich f\u00fcr unterschiedliche St\u00fccke beziehungsweise sind diese auf unterschiedliche Gitarren angepasst, die ja nun einmal unterschiedlich klingen. Soundtechnisch basiert das alles auf dem <strong><a href=\"http:\/\/www.thomann.de\/de\/mesa_boogie_triple_rectifer.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Mesa Triple Rectifier<\/a><\/strong>, den ich normalerweise, wenn ich echte Amps spiele, spiele. Oder alternativ f\u00fcr manche Sachen benutz ich einen <strong><a href=\"http:\/\/www.thomann.de\/de\/friedman_amplification_brown_eye_be_100.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Friedman BE<\/a><\/strong> im Fractal. Alle Effekte und alle Sounds gehen direkt ins Pult. Wir spielen mit InEar, daher brauchen wir auf der B\u00fchne keine Boxen. Und wie es so sch\u00f6n hei\u00dft: Je leiser es auf der B\u00fchne ist, desto besser klingt es, weil wenn ich meinen Rectifier auf der B\u00fchne aufrei\u00dfe, blase ich in jedes Mikro rein. Das macht den Mix nicht unbedingt optimaler. Ich rufe alle Sounds selbst \u00fcber die fractaleigene Fu\u00dfleiste ab, den <strong>MFC-101<\/strong>. Hab noch ein <strong><a href=\"http:\/\/www.thomann.de\/de\/mission_engineering_ep1_bk.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Mission-Expression-Pedal<\/a> <\/strong>dran, mit dem ich das <strong>Wah<\/strong> im Fractal steuere, wenn ich es einmal spiele. Und ich benutze zwei <a href=\"http:\/\/www.thomann.de\/de\/sennheiser.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Sennheiser<\/strong><\/a> <strong>Senderstrecken<\/strong>. Das hei\u00dft, wenn ich eine Gitarre wechsle, schaltet mein Roadie einfach an einem <strong><a href=\"http:\/\/www.thomann.de\/de\/morley_quad.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Morley <\/a><a href=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-26304\" src=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-4-225x300.jpg\" alt=\"Das Rack mit Sennheiser-Funk, AXE-FX und Morley Switcher\" width=\"213\" height=\"281\" \/><\/a><a href=\"http:\/\/www.thomann.de\/de\/morley_quad.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Switcher<\/a><\/strong> auf den anderen Sender um und ich kann nahtlos weiterspielen. Ist ein sehr simples Setup, sehr effektiv, klingt hervorragend. Also wie gesagt: Alle EQs am Pult sind komplett flat. Was man \u00fcber die PA h\u00f6rt oder was ich im InEar hab ist exakt das, was ich rausschicke; es wird nichts mehr nachbearbeitet. Was den Vorteil hat, dass du jeden Tag gleich klingst, weil du auch von der Raumakustik nicht abh\u00e4ngig bist. Und ich brauche keinen Soundcheck. Ich steck ein Kabel rein und kann anfangen. Ich wei\u00df genau wie es klingt, jeder wei\u00df genau wie es klingt. Und das System ist live meiner Meinung nach zurzeit nicht zu toppen. Vollkommen stressfrei, keinerlei St\u00f6ranf\u00e4lligkeiten bis jetzt und ich benutze es seit Jahren \u2013 hervorragend.\u201c<\/p>\n<p><strong>Wenn du dir neue Gitarren kaufst, baust du dann sofort deine Lieblingspickups drauf?<\/strong><\/p>\n<p>\u201eIch habe meine erste Les Paul irgendwann Mitte der <strong>90er<\/strong> gekauft. Weil ich einfach immer eine haben wollte, weil ich sie wundersch\u00f6n fand. Und die hat mich so \u201eangefixt\u201c, dass ich seitdem eigentlich nichts mehr anderes gespielt habe. Meine ganzen Gitarren sind eigentlich <a href=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-26305\" src=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-5-300x225.jpg\" alt=\"Marcus' Flying V\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-5-300x225.jpg 300w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-5-1024x769.jpg 1024w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-5-768x577.jpg 768w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-5.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><strong>Stock<\/strong>. Das einzige, das ich \u00e4ndere, sind teilweise die <strong>Pickups<\/strong>, um verschiedene Klangfarben zu erhalten. Wobei ich genug Gitarren habe, wo die originalen <a href=\"http:\/\/www.thomann.de\/de\/gibson_pickups_und_tonabnehmer.html?viewMode=block\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Gibson-Tonabnehmer<\/strong><\/a> noch drin sind. Gerade die <strong>Burstbucker<\/strong> klingen hervorragend. Das einzige, was ich optisch wirklich mal \u201egepimpt\u201c habe, war meine <strong>Flying V<\/strong>. Das war die normale, klassische, schwarze Flying V mit wei\u00dfem Schlagbrett. Das Wei\u00dfe hab ich durch ein Spiegelschlagbrett ersetzt, weil es mir einfach besser gefallen hat. Ansonsten w\u00fcsste ich nicht, was ich an den Gitarren \u00e4ndern sollte, um sie zu verbessern. Weil eine <strong>Les Paul<\/strong> nehme ich in die Hand \u2013 du kannst mir jetzt irgendeine Les Paul aus dem Shop geben, ich werde damit den Gig spielen k\u00f6nnen, ich werde damit im <strong>Studio<\/strong> problemlos arbeiten k\u00f6nnen \u2013 das ist eine Gitarre, die ist wie f\u00fcr mich gemacht. Also was auch immer Les Paul sich damals ausgedacht hat, er hat meinen Geschmack getroffen.\u201c<\/p>\n<p><strong>Also so ein bisschen das Brian-May-Prinzip \u2013 quasi mit einem Werkst\u00fcck zufrieden?<\/strong><\/p>\n<p>\u201eSchon, wobei \u2013 ich bin jemand, der immer mit einem ganzen <strong>Haufen an Gitarren<\/strong> auf <strong>Tour<\/strong> geht. Ich bin nicht jemand, der ein Set mit einer Gitarre durchspielt. Normalerweise wechsle ich nach drei St\u00fccken. Heute k\u00f6nnte es wegen der K\u00e4lte h\u00e4ufiger werden. Wir m\u00fcssen schauen, wie die Gitarren <strong>in tune<\/strong> bleiben. Und ich bin nicht jemand, der auf der B\u00fchne selbst sagt: \u201eMoment, ich muss eben nachstimmen!\u201c \u2013 sondern ich wechsele dann. Ich hab jetzt zehn Gitarren dabei. Von daher ist es nicht so, dass ich wirklich nur eine spiele. Aber im Prinzip ja: <a href=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-26306 alignright\" src=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-6-300x225.jpg\" alt=\"Die Les Paul Classic Closeup\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-6-300x225.jpg 300w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-6-1024x769.jpg 1024w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-6-768x577.jpg 768w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-6.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Ich brauche nicht irgendwas, das speziell auf mich zugeschnitten ist, eine Gibson passt. Ich mag die <strong>H\u00e4lse<\/strong>, ich war immer ein Fan von denen \u2013 manche nennen sie Baseballschl\u00e4ger \u2013 aber ich mag halt diesen dicken Hals. Zum einen macht es sich im <strong>Ton<\/strong> der Gitarre bemerkbar, weil du einfach mehr Holz hast und es klingt \u201e<strong>fetter<\/strong>\u201c. Und ich mag es auch vom <strong>Spielgef\u00fchl<\/strong> lieber, weil bei diesen ultrad\u00fcnnen, flachen <strong>Shredder-H\u00e4lsen<\/strong>, da habe ich immer das Gef\u00fchl, entweder nichts in der Hand zu haben oder es gleich durchzubrechen. Das ist nie mein Ding gewesen. Ich bin eh kein Shredder, von daher brauche ich den Hals nicht so. Irgendeine Les Paul funktioniert f\u00fcr mich, eine Explorer. Die SG hab ich erst seit drei oder vier Tagen. Die ist Neuland, aber auch die funktioniert f\u00fcr mich perfekt. Flying V, geht alles.\u201c<\/p>\n<p><strong>Welche Saitenst\u00e4rken spielst du?<\/strong><\/p>\n<p><a href=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-26307\" src=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-7-300x225.jpg\" alt=\"Marcus mit seiner 7-Saiter SG\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-7-300x225.jpg 300w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-7-1024x769.jpg 1024w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-7-768x577.jpg 768w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-7.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u201eIch spiele <strong><a href=\"http:\/\/www.thomann.de\/de\/daddario.html\" target=\"_blank\" rel=\"noopener noreferrer\">Daddario<\/a>-Saiten<\/strong>. Bei den sechssaitigen spiele ich den <strong>Light-Top-Heavy-Bottom<\/strong> \u2013 das sind die <a href=\"http:\/\/www.thomann.de\/de\/search_dir.html?bf=&amp;sw=NYXL+S%E4tze&amp;viewMode=block\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>NYXL S\u00e4tze<\/strong><\/a>. <strong><a href=\"http:\/\/www.thomann.de\/de\/daddario_nyxl1052.htm?ref=search_prv_0_1\" target=\"_blank\" rel=\"noopener noreferrer\">10-52er<\/a><\/strong> \u2013 die d\u00fcnnen drei Saiten sind aus einem 10er Satz, die tiefen aus einem <strong>12er Satz<\/strong>. Und f\u00fcr die Siebensaiter kommt eine individuelle <strong>63er-Saite<\/strong> als siebte Saite dazu. Das hei\u00dft, ich spiele den normalen 6er-Satz und haue die zus\u00e4tzliche Saite darauf. Zu dem Zeitpunkt, als ich angefangen habe, <strong>Siebensaiter<\/strong> zu benutzen, gab es von Daddario keinen Siebensaitersatz in der St\u00e4rke, die ich brauchte. Das ging alles nur bis 59. Da die Gibsons eine kurze Mensur haben, die klassische <strong>Gibson-Mensur<\/strong> eben, und wir immer noch einen Halbton herunterstimmen, war mir das zu \u201eschlabbrig\u201c alles. Ich brauchte dickere Saiten und habe dann mit Daddario gesprochen: \u201eK\u00f6nnt ihr Einzelsaiten schicken? Schickt mir mal von \u2026 bis \u2026 und ich teste durch!\u201c Und dann hat sich also die Kombination von meinem normalen Satz plus diese 63er f\u00fcr mich als wunderbar erwiesen.\u201c<\/p>\n<p><strong>Du wirst ja vorher auch die normalen S\u00e4tze gespielt haben von Daddario, bevor es die NYXL gab, hast du da einen Unterschied feststellen k\u00f6nnen?<\/strong><\/p>\n<p>\u201eSie klingen l\u00e4nger frisch, muss ich tats\u00e4chlich sagen. Auf <strong>Tour<\/strong> wechseln wir alle drei oder vier Tage. Es sei denn, ich spiel eine Gitarre wirklich sehr lange durch, dann hauen wir auch am n\u00e4chsten Tag schon einmal frische<strong> Saiten<\/strong> drauf \u2013 um einfach zu verhindern, dass mir w\u00e4hrend dem <strong>Gig<\/strong> eine Saite rei\u00dft, weil das ist immer bl\u00f6d. Wobei ich mich an die letzte gerissene Saite ehrlich gesagt nicht mehr erinnern kann, das ist sehr lange her. Aber im Studio oder wenn ich zu Hause einfach mit einer Gitarre spiele, dann merke ich, dass die neuen S\u00e4tze l\u00e4nger frisch klingen. Es ist wirklich ein Unterschied.\u201c<\/p>\n<p><strong>Wie wichtig ist Produktionstechnik f\u00fcr dich, also InEar usw. f\u00fcr das Konzerterlebnis?<\/strong><\/p>\n<p>\u201eSehr wichtig. Wir sind vor einer ganzen Weile schon auf <a href=\"http:\/\/www.thomann.de\/de\/in_ear_monitoring.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>InEar<\/strong><\/a> umgestiegen. Hansi, unser S\u00e4nger, ist im Jahr 98 auf InEar gewechselt und wir sind 2002 nachgezogen. Egal, wo du dich auf der <strong>B\u00fchne<\/strong> bewegst, der Sound \u00e4ndert sich nicht. Fr\u00fcher, wenn du normal mit Amp und Box gespielt hast: Du hast irgendwo deinen \u201e<strong>Sweet-Spot<\/strong>\u201c, wo es richtig gut klingt, aber mache einen Schritt nach rechts und es klingt nicht mehr so \u2013 und mach zwei Schritte nach rechts und der Sound \u00e4ndert sich komplett. Wenn du vor dem Schlagzeug stehst, h\u00f6rst du nichts anderes mehr. Wenn ich auf Andr\u00e9s Seite gegangen bin, dann habe ich nur ihn geh\u00f6rt. <a href=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-23.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-26325 size-medium\" src=\"https:\/\/www.thomann.de\/blog\/wp-content\/uploads\/2016\/05\/rig-rundown-interview-mit-blind-guardian-23-300x225.jpg\" alt=\"Blind Guardion on stage\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-23-300x225.jpg 300w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-23-1024x769.jpg 1024w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-23-768x577.jpg 768w, https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-23.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Wenn er bei mir war, dann hat er nur mich geh\u00f6rt. Und mit InEar kannst du halt machen, was du willst. Jeder hat seinen individuellen Sound, keiner st\u00f6rt den anderen mit individuellen Soundw\u00fcnschen. Du kannst die Lautst\u00e4rke selbst kontrollieren. Dadurch k\u00f6nnen wir direkt ins Pult mit Fractal spielen und Andr\u00e9 mit seinem <a href=\"http:\/\/www.thomann.de\/de\/kemper.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Kemper<\/strong><\/a>. Wir sind von Boxen komplett unabh\u00e4ngig, dadurch wird es auf der B\u00fchne leiser. Du hast nicht so viele Einstreuungen \u00fcber <strong>Gesangs- oder Schlagzeugmikros<\/strong>, bei welchen du normalerweise immer<strong> Gitarrensignale<\/strong> auch mit dranh\u00e4ngen hast \u2013 weil einfach die Gitarren auf der B\u00fchne so laut waren. Es hat nur Vorteile. Es war am Anfang eine Umstellung, weil du nat\u00fcrlich relativ abgeschottet bist.<\/p>\n<p>Und ich kann mich an eine <strong>Show in Italien<\/strong> erinnern: Wir haben gespielt und beim Gig war alles cool. Wir sind dann von der B\u00fchne runter f\u00fcr die Zugaben und haben halt gewartet, dass die Fans nach uns rufen, haben nichts geh\u00f6rt und waren irgendwann so angepisst, sodass wir gedacht haben: \u201eOkay, wenn ihr nicht wollt, dann eben nicht, dann gehen wir.\u201c Gitarren abgegeben \u2013 ihr k\u00f6nnt abbauen! Und alle schauten nur und als die Crew abgebaut hat, kamen sie in den Nightliner: \u201eWarum habt ihr die Zugaben nicht gespielt?\u201c \u201eWieso, da war Totenstille, es hat keiner etwas gerufen!\u201c \u201eDie haben sich die Seele aus dem Hals geschrien!\u201c Und wir haben mit den Kopfh\u00f6rern nichts geh\u00f6rt und seitdem haben wir Mikros, die uns das Publikum mit auf dem Mix geben. Seitdem ist das nicht mehr passiert. Wir haben sp\u00e4ter, im n\u00e4chsten Jahr, in derselben Stadt kleinlaut eine sehr lange Show gespielt. Das sind so die Pannen, die man am Anfang macht, da muss man sich erst dran gew\u00f6hnen.\u201c<\/p>\n<p><strong>Impressionen vom Rock Hard<\/strong><\/p>\n\n\t\t<style>\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-26290 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-17-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-22-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-24-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.thomann.de\/blog\/app\/uploads\/sites\/2\/2016\/05\/rig-rundown-interview-mit-blind-guardian-21-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>PS: Peter, der Gewinner der Rock-Hard-VIP-Trip, hat uns ein paar Zeilen und Fotos zu seinem Wochenende auf dem Rock Hard Festival 2016 zukommen lassen. Was er zu erz\u00e4hlen hat, erfahrt ihr <a href=\"https:\/\/www.thomann.de\/blog\/de\/gewinne-vip-tickets-fuers-rock-hard-festival-m\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>unter diesem Link<\/strong><\/a>.<br \/>\n<strong><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gitarrist Marcus Siepen hat uns auf dem Rock Hard Festival 2016 exklusiv sein Setup vorgestellt \u2026<\/p>\n","protected":false},"author":16,"featured_media":26291,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tblog_post_audio_url":"","footnotes":""},"categories":[10686],"tags":[],"class_list":["post-26290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspire"],"category_colors":{"color_key":"inspire","css_classes":{"text":"cat-inspire","text_light":"cat-inspire-light","bg":"cat-bg-inspire","bg_light":"cat-bg-inspire-light","border":"cat-border-inspire","text_on_bg":"cat-text-on-inspire"}},"reading_time":{"minutes":10,"formatted":"10 Min."},"_links":{"self":[{"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/posts\/26290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/comments?post=26290"}],"version-history":[{"count":0,"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/posts\/26290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/media\/26291"}],"wp:attachment":[{"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/media?parent=26290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/categories?post=26290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thomann.de\/blog\/de\/wp-json\/wp\/v2\/tags?post=26290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}